{"id":7,"count":14,"description":"","link":"https:\/\/blog.traveleurope.com\/en\/oddities\/","name":"Oddities","slug":"oddities","taxonomy":"category","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Oddities Archives - Traveleurope Blog | Travel tips, advices and useful info<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blog.traveleurope.com\/en\/oddities\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Oddities Archives - Traveleurope Blog | Travel tips, advices and useful info\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blog.traveleurope.com\/en\/oddities\/\" \/>\n<meta property=\"og:site_name\" content=\"Traveleurope Blog | Travel tips, advices and useful info\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@TraveleuropeEN\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/blog.traveleurope.com\\\/en\\\/oddities\\\/\",\"url\":\"https:\\\/\\\/blog.traveleurope.com\\\/en\\\/oddities\\\/\",\"name\":\"Oddities Archives - Traveleurope Blog | Travel tips, advices and useful info\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.traveleurope.com\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blog.traveleurope.com\\\/en\\\/oddities\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blog.traveleurope.com\\\/en\\\/oddities\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/blog.traveleurope.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Oddities\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blog.traveleurope.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/blog.traveleurope.com\\\/en\\\/\",\"name\":\"Traveleurope Blog | Travel tips, advices and useful info\",\"description\":\"A Blog full of ideas, travel tips and guides, suggestions and anecdotes to discover the hidden treasures of the major cities in Italy and Europe\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blog.traveleurope.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Oddities Archives - Traveleurope Blog | Travel tips, advices and useful info","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blog.traveleurope.com\/en\/oddities\/","og_locale":"en_US","og_type":"article","og_title":"Oddities Archives - Traveleurope Blog | Travel tips, advices and useful info","og_url":"https:\/\/blog.traveleurope.com\/en\/oddities\/","og_site_name":"Traveleurope Blog | Travel tips, advices and useful info","twitter_card":"summary_large_image","twitter_site":"@TraveleuropeEN","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/blog.traveleurope.com\/en\/oddities\/","url":"https:\/\/blog.traveleurope.com\/en\/oddities\/","name":"Oddities Archives - Traveleurope Blog | Travel tips, advices and useful info","isPartOf":{"@id":"https:\/\/blog.traveleurope.com\/en\/#website"},"breadcrumb":{"@id":"https:\/\/blog.traveleurope.com\/en\/oddities\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/blog.traveleurope.com\/en\/oddities\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/blog.traveleurope.com\/en\/"},{"@type":"ListItem","position":2,"name":"Oddities"}]},{"@type":"WebSite","@id":"https:\/\/blog.traveleurope.com\/en\/#website","url":"https:\/\/blog.traveleurope.com\/en\/","name":"Traveleurope Blog | Travel tips, advices and useful info","description":"A Blog full of ideas, travel tips and guides, suggestions and anecdotes to discover the hidden treasures of the major cities in Italy and Europe","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blog.traveleurope.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/blog.traveleurope.com\/en\/wp-json\/wp\/v2\/categories\/7","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.traveleurope.com\/en\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/blog.traveleurope.com\/en\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/blog.traveleurope.com\/en\/wp-json\/wp\/v2\/posts?categories=7"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}